{"id":10301,"date":"2026-03-21T11:26:02","date_gmt":"2026-03-21T10:26:02","guid":{"rendered":"https:\/\/maristeurope.eu\/celebration-de-lannee-saint-francois-dassise\/"},"modified":"2026-03-31T21:00:40","modified_gmt":"2026-03-31T19:00:40","slug":"celebration-de-lannee-saint-francois-dassise","status":"publish","type":"post","link":"https:\/\/maristeurope.eu\/fr\/celebration-de-lannee-saint-francois-dassise\/","title":{"rendered":"C\u00e9l\u00e9bration de l&rsquo;ann\u00e9e Saint Fran\u00e7ois d&rsquo;Assise"},"content":{"rendered":"\n<p class=\"has-medium-font-size\"><strong>Renato Frappi<\/strong> raconte son <strong>exp\u00e9rience avec Saint Fran\u00e7ois d'Assise :<\/strong> Les 24 et 25 f\u00e9vrier, j'ai eu la merveilleuse opportunit\u00e9 de visiter Assise \u00e0 l'occasion du 800e anniversaire de la mort de saint Fran\u00e7ois. J'ai v\u00e9cu ces deux jours comme tr\u00e8s profonds, en particulier la v\u00e9n\u00e9ration de la d\u00e9pouille mortelle de Fran\u00e7ois. J'ai toujours consid\u00e9r\u00e9 Fran\u00e7ois comme un homme qui a apport\u00e9 une \u00e9norme contribution dans de nombreux domaines, de la culture aux arts visuels, de l'\u00e9cologie \u00e0 la litt\u00e9rature italienne. Mais cette fois, je ne me suis pas arr\u00eat\u00e9 \u00e0 \"ce\" Fran\u00e7ois. Alors que je faisais la queue avec de nombreux autres p\u00e8lerins pour voir sa d\u00e9pouille mortelle, j'ai r\u00e9fl\u00e9chi \u00e0 sa vie et \u00e0 son choix radical, qui \u00e9tait profond\u00e9ment diff\u00e9rent de celui de la plupart de ceux qui le v\u00e9n\u00e8rent, l'estiment et l'aiment aujourd'hui, moi y compris. Son existence a \u00e9t\u00e9 si aust\u00e8re et joyeuse, mais riche en Esprit et en relations, qu'elle peut souvent sembler inaccessible, in\u00e9gal\u00e9e.     <\/p>\n\n<p class=\"has-medium-font-size\">En regardant pendant quelques instants ces pauvres os que tout le monde peut maintenant v\u00e9n\u00e9rer, j'ai senti en moi une forte attirance pour ce petit mais grand homme qui a renouvel\u00e9 l'\u00c9glise et a donn\u00e9 confiance et espoir aux plus pauvres et aux plus malheureux. J'ai red\u00e9couvert l'urgence de remettre J\u00e9sus et l'\u00c9vangile au centre, de cultiver une relation avec Lui pour une vie de foi, de le conna\u00eetre \u00e0 travers sa Parole, d'\u00eatre le reflet de sa pr\u00e9sence constante dans l'histoire, de pouvoir reconna\u00eetre dans l'autre et dans la cr\u00e9ation l'action de l'Esprit qui conduit toujours \u00e0 la pr\u00e9servation de la communion fraternelle et universelle. Ce fut pour moi une exp\u00e9rience importante et profonde, rendue encore plus joyeuse par les autres compagnons exceptionnels que j'ai rencontr\u00e9s \u00e0 Assise : Chiara, la douce et forte compagne de Fran\u00e7ois, et Carlo Acutis, le jeune homme amoureux de l'Eucharistie. Quelle gr\u00e2ce \u00e0 Assise !   <\/p>\n\n<p><\/p>\n\n<figure class=\"wp-block-image\"><img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1442\" src=\"https:\/\/maristeurope.eu\/wp-content\/uploads\/2026\/03\/20260225_081634-scaled.jpg\" alt=\"\" class=\"wp-image-10282\" srcset=\"https:\/\/maristeurope.eu\/wp-content\/uploads\/2026\/03\/20260225_081634-scaled.jpg 2560w, https:\/\/maristeurope.eu\/wp-content\/uploads\/2026\/03\/20260225_081634-1280x721.jpg 1280w, https:\/\/maristeurope.eu\/wp-content\/uploads\/2026\/03\/20260225_081634-980x552.jpg 980w, https:\/\/maristeurope.eu\/wp-content\/uploads\/2026\/03\/20260225_081634-480x270.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) and (max-width: 1280px) 1280px, (min-width: 1281px) 2560px, 100vw\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Une ann\u00e9e jubilaire sp\u00e9ciale de saint Fran\u00e7ois se d\u00e9roulera \u00e0 Assise du 10 janvier 2026 au 10 janvier 2027, pour c\u00e9l\u00e9brer le 800e anniversaire de la mort du saint (1226-2026). Proclam\u00e9e par le pape L\u00e9on XIV, cette \"Ann\u00e9e de saint Fran\u00e7ois\" est l&rsquo;occasion d&rsquo;une rare exposition publique de la d\u00e9pouille de saint Fran\u00e7ois.   <\/p>\n","protected":false},"author":3,"featured_media":10277,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[48],"tags":[],"class_list":["post-10301","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-non-categorise"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>C\u00e9l\u00e9bration de l&#039;ann\u00e9e Saint Fran\u00e7ois d&#039;Assise - Marist Europe<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/maristeurope.eu\/fr\/celebration-de-lannee-saint-francois-dassise\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"C\u00e9l\u00e9bration de l&#039;ann\u00e9e Saint Fran\u00e7ois d&#039;Assise - Marist Europe\" \/>\n<meta property=\"og:description\" content=\"Une ann\u00e9e jubilaire sp\u00e9ciale de saint Fran\u00e7ois se d\u00e9roulera \u00e0 Assise du 10 janvier 2026 au 10 janvier 2027, pour c\u00e9l\u00e9brer le 800e anniversaire de la mort du saint (1226-2026). Proclam\u00e9e par le pape L\u00e9on XIV, cette &quot;Ann\u00e9e de saint Fran\u00e7ois&quot; est l&#039;occasion d&#039;une rare exposition publique de la d\u00e9pouille de saint Fran\u00e7ois.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/maristeurope.eu\/fr\/celebration-de-lannee-saint-francois-dassise\/\" \/>\n<meta property=\"og:site_name\" content=\"Marist Europe\" \/>\n<meta property=\"article:published_time\" content=\"2026-03-21T10:26:02+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-31T19:00:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/maristeurope.eu\/wp-content\/uploads\/2026\/03\/20260225_124158-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1442\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Anne Marie Salgo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Anne Marie Salgo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/maristeurope.eu\\\/fr\\\/celebration-de-lannee-saint-francois-dassise\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/maristeurope.eu\\\/fr\\\/celebration-de-lannee-saint-francois-dassise\\\/\"},\"author\":{\"name\":\"Anne Marie Salgo\",\"@id\":\"https:\\\/\\\/maristeurope.eu\\\/fr\\\/#\\\/schema\\\/person\\\/52ef67935880edd2768565651118bee9\"},\"headline\":\"C\u00e9l\u00e9bration de l&rsquo;ann\u00e9e Saint Fran\u00e7ois d&rsquo;Assise\",\"datePublished\":\"2026-03-21T10:26:02+00:00\",\"dateModified\":\"2026-03-31T19:00:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/maristeurope.eu\\\/fr\\\/celebration-de-lannee-saint-francois-dassise\\\/\"},\"wordCount\":373,\"publisher\":{\"@id\":\"https:\\\/\\\/maristeurope.eu\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/maristeurope.eu\\\/fr\\\/celebration-de-lannee-saint-francois-dassise\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/maristeurope.eu\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/20260225_124158-scaled.jpg\",\"articleSection\":[\"Non cat\u00e9goris\u00e9\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/maristeurope.eu\\\/fr\\\/celebration-de-lannee-saint-francois-dassise\\\/\",\"url\":\"https:\\\/\\\/maristeurope.eu\\\/fr\\\/celebration-de-lannee-saint-francois-dassise\\\/\",\"name\":\"C\u00e9l\u00e9bration de l'ann\u00e9e Saint Fran\u00e7ois d'Assise - Marist Europe\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/maristeurope.eu\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/maristeurope.eu\\\/fr\\\/celebration-de-lannee-saint-francois-dassise\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/maristeurope.eu\\\/fr\\\/celebration-de-lannee-saint-francois-dassise\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/maristeurope.eu\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/20260225_124158-scaled.jpg\",\"datePublished\":\"2026-03-21T10:26:02+00:00\",\"dateModified\":\"2026-03-31T19:00:40+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/maristeurope.eu\\\/fr\\\/celebration-de-lannee-saint-francois-dassise\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/maristeurope.eu\\\/fr\\\/celebration-de-lannee-saint-francois-dassise\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/maristeurope.eu\\\/fr\\\/celebration-de-lannee-saint-francois-dassise\\\/#primaryimage\",\"url\":\"https:\\\/\\\/maristeurope.eu\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/20260225_124158-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/maristeurope.eu\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/20260225_124158-scaled.jpg\",\"width\":2560,\"height\":1442},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/maristeurope.eu\\\/fr\\\/celebration-de-lannee-saint-francois-dassise\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/maristeurope.eu\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"C\u00e9l\u00e9bration de l&#8217;ann\u00e9e Saint Fran\u00e7ois d&#8217;Assise\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/maristeurope.eu\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/maristeurope.eu\\\/fr\\\/\",\"name\":\"Marist Europe\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/maristeurope.eu\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/maristeurope.eu\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/maristeurope.eu\\\/fr\\\/#organization\",\"name\":\"Marist Europe\",\"url\":\"https:\\\/\\\/maristeurope.eu\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/maristeurope.eu\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/maristeurope.eu\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/EU-SM-Finalogo-02.png\",\"contentUrl\":\"https:\\\/\\\/maristeurope.eu\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/EU-SM-Finalogo-02.png\",\"width\":150,\"height\":156,\"caption\":\"Marist Europe\"},\"image\":{\"@id\":\"https:\\\/\\\/maristeurope.eu\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/maristeurope.eu\\\/fr\\\/#\\\/schema\\\/person\\\/52ef67935880edd2768565651118bee9\",\"name\":\"Anne Marie Salgo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/63bc5f7f74a90bb8d99eaaf8206d8217d780934d9a9659350347a36f2698fe6b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/63bc5f7f74a90bb8d99eaaf8206d8217d780934d9a9659350347a36f2698fe6b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/63bc5f7f74a90bb8d99eaaf8206d8217d780934d9a9659350347a36f2698fe6b?s=96&d=mm&r=g\",\"caption\":\"Anne Marie Salgo\"},\"url\":\"https:\\\/\\\/maristeurope.eu\\\/fr\\\/author\\\/anne\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"C\u00e9l\u00e9bration de l'ann\u00e9e Saint Fran\u00e7ois d'Assise - Marist Europe","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/maristeurope.eu\/fr\/celebration-de-lannee-saint-francois-dassise\/","og_locale":"fr_FR","og_type":"article","og_title":"C\u00e9l\u00e9bration de l'ann\u00e9e Saint Fran\u00e7ois d'Assise - Marist Europe","og_description":"Une ann\u00e9e jubilaire sp\u00e9ciale de saint Fran\u00e7ois se d\u00e9roulera \u00e0 Assise du 10 janvier 2026 au 10 janvier 2027, pour c\u00e9l\u00e9brer le 800e anniversaire de la mort du saint (1226-2026). Proclam\u00e9e par le pape L\u00e9on XIV, cette \"Ann\u00e9e de saint Fran\u00e7ois\" est l'occasion d'une rare exposition publique de la d\u00e9pouille de saint Fran\u00e7ois.","og_url":"https:\/\/maristeurope.eu\/fr\/celebration-de-lannee-saint-francois-dassise\/","og_site_name":"Marist Europe","article_published_time":"2026-03-21T10:26:02+00:00","article_modified_time":"2026-03-31T19:00:40+00:00","og_image":[{"width":2560,"height":1442,"url":"https:\/\/maristeurope.eu\/wp-content\/uploads\/2026\/03\/20260225_124158-scaled.jpg","type":"image\/jpeg"}],"author":"Anne Marie Salgo","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Anne Marie Salgo","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/maristeurope.eu\/fr\/celebration-de-lannee-saint-francois-dassise\/#article","isPartOf":{"@id":"https:\/\/maristeurope.eu\/fr\/celebration-de-lannee-saint-francois-dassise\/"},"author":{"name":"Anne Marie Salgo","@id":"https:\/\/maristeurope.eu\/fr\/#\/schema\/person\/52ef67935880edd2768565651118bee9"},"headline":"C\u00e9l\u00e9bration de l&rsquo;ann\u00e9e Saint Fran\u00e7ois d&rsquo;Assise","datePublished":"2026-03-21T10:26:02+00:00","dateModified":"2026-03-31T19:00:40+00:00","mainEntityOfPage":{"@id":"https:\/\/maristeurope.eu\/fr\/celebration-de-lannee-saint-francois-dassise\/"},"wordCount":373,"publisher":{"@id":"https:\/\/maristeurope.eu\/fr\/#organization"},"image":{"@id":"https:\/\/maristeurope.eu\/fr\/celebration-de-lannee-saint-francois-dassise\/#primaryimage"},"thumbnailUrl":"https:\/\/maristeurope.eu\/wp-content\/uploads\/2026\/03\/20260225_124158-scaled.jpg","articleSection":["Non cat\u00e9goris\u00e9"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/maristeurope.eu\/fr\/celebration-de-lannee-saint-francois-dassise\/","url":"https:\/\/maristeurope.eu\/fr\/celebration-de-lannee-saint-francois-dassise\/","name":"C\u00e9l\u00e9bration de l'ann\u00e9e Saint Fran\u00e7ois d'Assise - Marist Europe","isPartOf":{"@id":"https:\/\/maristeurope.eu\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/maristeurope.eu\/fr\/celebration-de-lannee-saint-francois-dassise\/#primaryimage"},"image":{"@id":"https:\/\/maristeurope.eu\/fr\/celebration-de-lannee-saint-francois-dassise\/#primaryimage"},"thumbnailUrl":"https:\/\/maristeurope.eu\/wp-content\/uploads\/2026\/03\/20260225_124158-scaled.jpg","datePublished":"2026-03-21T10:26:02+00:00","dateModified":"2026-03-31T19:00:40+00:00","breadcrumb":{"@id":"https:\/\/maristeurope.eu\/fr\/celebration-de-lannee-saint-francois-dassise\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/maristeurope.eu\/fr\/celebration-de-lannee-saint-francois-dassise\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/maristeurope.eu\/fr\/celebration-de-lannee-saint-francois-dassise\/#primaryimage","url":"https:\/\/maristeurope.eu\/wp-content\/uploads\/2026\/03\/20260225_124158-scaled.jpg","contentUrl":"https:\/\/maristeurope.eu\/wp-content\/uploads\/2026\/03\/20260225_124158-scaled.jpg","width":2560,"height":1442},{"@type":"BreadcrumbList","@id":"https:\/\/maristeurope.eu\/fr\/celebration-de-lannee-saint-francois-dassise\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/maristeurope.eu\/fr\/"},{"@type":"ListItem","position":2,"name":"C\u00e9l\u00e9bration de l&#8217;ann\u00e9e Saint Fran\u00e7ois d&#8217;Assise"}]},{"@type":"WebSite","@id":"https:\/\/maristeurope.eu\/fr\/#website","url":"https:\/\/maristeurope.eu\/fr\/","name":"Marist Europe","description":"","publisher":{"@id":"https:\/\/maristeurope.eu\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/maristeurope.eu\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/maristeurope.eu\/fr\/#organization","name":"Marist Europe","url":"https:\/\/maristeurope.eu\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/maristeurope.eu\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/maristeurope.eu\/wp-content\/uploads\/2024\/10\/EU-SM-Finalogo-02.png","contentUrl":"https:\/\/maristeurope.eu\/wp-content\/uploads\/2024\/10\/EU-SM-Finalogo-02.png","width":150,"height":156,"caption":"Marist Europe"},"image":{"@id":"https:\/\/maristeurope.eu\/fr\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/maristeurope.eu\/fr\/#\/schema\/person\/52ef67935880edd2768565651118bee9","name":"Anne Marie Salgo","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/63bc5f7f74a90bb8d99eaaf8206d8217d780934d9a9659350347a36f2698fe6b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/63bc5f7f74a90bb8d99eaaf8206d8217d780934d9a9659350347a36f2698fe6b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/63bc5f7f74a90bb8d99eaaf8206d8217d780934d9a9659350347a36f2698fe6b?s=96&d=mm&r=g","caption":"Anne Marie Salgo"},"url":"https:\/\/maristeurope.eu\/fr\/author\/anne\/"}]}},"_links":{"self":[{"href":"https:\/\/maristeurope.eu\/fr\/wp-json\/wp\/v2\/posts\/10301","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/maristeurope.eu\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/maristeurope.eu\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/maristeurope.eu\/fr\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/maristeurope.eu\/fr\/wp-json\/wp\/v2\/comments?post=10301"}],"version-history":[{"count":1,"href":"https:\/\/maristeurope.eu\/fr\/wp-json\/wp\/v2\/posts\/10301\/revisions"}],"predecessor-version":[{"id":10302,"href":"https:\/\/maristeurope.eu\/fr\/wp-json\/wp\/v2\/posts\/10301\/revisions\/10302"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/maristeurope.eu\/fr\/wp-json\/wp\/v2\/media\/10277"}],"wp:attachment":[{"href":"https:\/\/maristeurope.eu\/fr\/wp-json\/wp\/v2\/media?parent=10301"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/maristeurope.eu\/fr\/wp-json\/wp\/v2\/categories?post=10301"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/maristeurope.eu\/fr\/wp-json\/wp\/v2\/tags?post=10301"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}