{"id":10576,"date":"2026-04-22T15:30:00","date_gmt":"2026-04-22T13:30:00","guid":{"rendered":"https:\/\/maristeurope.eu\/los-padres-maristas-se-unen-a-la-provincia-de-europa\/"},"modified":"2026-05-13T15:49:13","modified_gmt":"2026-05-13T13:49:13","slug":"los-padres-maristas-se-unen-a-la-provincia-de-europa","status":"publish","type":"post","link":"https:\/\/maristeurope.eu\/es\/los-padres-maristas-se-unen-a-la-provincia-de-europa\/","title":{"rendered":"Los Padres Maristas se unen a la Provincia de Europa"},"content":{"rendered":"\n<p class=\"has-text-align-left\"><strong>PRIMEROS PASOS EN LYON: UNA EXPERIENCIA RICA Y FRATERNAL<br\/><\/strong>Mi llegada a Lyon en septiembre de 2025 estuvo marcada por una calurosa acogida: El P. Roger Lordong hab\u00eda venido a recibirme a la estaci\u00f3n de Lyon Perrache, un gesto sencillo pero profundamente fraternal que marc\u00f3 el tono de esta nueva etapa de mi vida como misionero marista. La vida comunitaria en la Rue Sala va tomando forma poco a poco. Poco a poco, se han ido forjando lazos a trav\u00e9s de comidas compartidas, conversaciones y momentos de oraci\u00f3n. La comunidad tambi\u00e9n sabe celebrar las alegr\u00edas sencillas de la vida: varios cumplea\u00f1os, entre ellos el m\u00edo en septiembre y el de Roger en febrero, momentos de convivencia que fortalecen nuestra fraternidad; varios acontecimientos comunitarios significativos: una reuni\u00f3n en la Rue Sala y otras dos con la comunidad m\u00e1s amplia de Neyli\u00e8re, la \u00faltima de las cuales fue organizada por las Hermanas SMSM. Estas reuniones han sido valiosas oportunidades para discutir nuestra misi\u00f3n y comprender mejor nuestro lugar dentro de nuestro compromiso. Adem\u00e1s, contin\u00fao mis estudios en ciencias de la educaci\u00f3n con el objetivo de convertirme en maestra de primaria. Actualmente estoy realizando pr\u00e1cticas supervisadas en Bellecombe, donde adquiero experiencia pr\u00e1ctica de la profesi\u00f3n. Estoy contenta de vivir en esta comunidad intergeneracional e internacional, en la que conviven cuatro nacionalidades distintas. Todo el mundo contribuye, y estoy aprendiendo mucho de los miembros de m\u00e1s edad. Es una experiencia profundamente enriquecedora.            <br\/><\/p>\n\n<p class=\"has-text-align-right\"><em>Christian Ngoura, sm<br\/><\/em><\/p>\n\n<p><strong>UN NUEVO COMIENZO LLENO DE ALEGR\u00cdA Y CONFIANZA<br\/><\/strong>Doy gracias a Dios por haberme permitido unirme a la comunidad de Notre Dame de France en Londres el 28 de febrero, tras una larga espera para obtener mi visado. All\u00ed recib\u00ed una acogida muy calurosa, que llen\u00f3 mi coraz\u00f3n de alegr\u00eda y me ayud\u00f3 inmediatamente a sentirme como en casa. Desde hace m\u00e1s de un mes, descubro poco a poco esta parroquia, que considero una verdadera escuela de vida cristiana y de servicio apost\u00f3lico. Cada d\u00eda aprendo a amar m\u00e1s profundamente y a servir con sencillez y apertura. Me voy asentando poco a poco, a trav\u00e9s de los diversos ministerios y encuentros que alimentan mi fe y me ayudan a crecer como persona: humana, espiritual, cultural y pastoralmente. Me conmueven el dinamismo, la apertura y la profundidad de fe de esta comunidad, que es un lugar precioso para m\u00ed. Tambi\u00e9n guardo en mi coraz\u00f3n el recuerdo del Padre Hubert, que fue llamado a Dios antes de mi llegada. Su testimonio sigue vivo entre nosotros. La primavera que ha comenzado refleja lo que experimento interiormente: una renovaci\u00f3n, una esperanza creciente y un coraz\u00f3n que se abre y permanece optimista. Sigo por este camino con confianza y alegr\u00eda, avanzando con todo el equipo, guiados por Mar\u00eda, nuestra Madre, para descubrir y realizar juntos el plan de Dios. Juntos estamos aprendiendo a reconocer la presencia de Dios en nuestra vida cotidiana, a crecer en la caridad y a dar testimonio del Evangelio con sencillez y esperanza.         <br\/><\/p>\n\n<p class=\"has-text-align-right\"><em>Clovis Gwencho, sm<\/em><\/p>\n\n<p class=\"has-text-align-right\"><\/p>\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image aligncenter size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"260\" height=\"328\" src=\"https:\/\/maristeurope.eu\/wp-content\/uploads\/2026\/04\/Capture-decran-2026-04-01-2.jpg\" alt=\"\" class=\"wp-image-10560\" style=\"aspect-ratio:3\/4;object-fit:cover;width:auto;height:400px\" srcset=\"https:\/\/maristeurope.eu\/wp-content\/uploads\/2026\/04\/Capture-decran-2026-04-01-2.jpg 260w, https:\/\/maristeurope.eu\/wp-content\/uploads\/2026\/04\/Capture-decran-2026-04-01-2-238x300.jpg 238w\" sizes=\"(max-width: 260px) 100vw, 260px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" src=\"https:\/\/maristeurope.eu\/wp-content\/uploads\/2026\/04\/IMG20260403155936-768x1024.jpg\" alt=\"\" class=\"wp-image-10567\" style=\"aspect-ratio:3\/4;object-fit:cover;width:auto;height:400px\"\/><\/figure>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Nos complace dar la bienvenida a la Provincia de Europa al Padre Christian, que vive con la comunidad de Lyon, y al Padre Clovis, que se une a la comunidad de Londres.<\/p>\n","protected":false},"author":7,"featured_media":10555,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[50],"tags":[],"class_list":["post-10576","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categoria"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Los Padres Maristas se unen a la Provincia de Europa - Marist Europe<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/maristeurope.eu\/es\/los-padres-maristas-se-unen-a-la-provincia-de-europa\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Los Padres Maristas se unen a la Provincia de Europa - Marist Europe\" \/>\n<meta property=\"og:description\" content=\"Nos complace dar la bienvenida a la Provincia de Europa al Padre Christian, que vive con la comunidad de Lyon, y al Padre Clovis, que se une a la comunidad de Londres.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/maristeurope.eu\/es\/los-padres-maristas-se-unen-a-la-provincia-de-europa\/\" \/>\n<meta property=\"og:site_name\" content=\"Marist Europe\" \/>\n<meta property=\"article:published_time\" content=\"2026-04-22T13:30:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-13T13:49:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/maristeurope.eu\/wp-content\/uploads\/2026\/04\/small-table-lamp-world-map-copy-space-1-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1707\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"theo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"theo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/maristeurope.eu\\\/es\\\/los-padres-maristas-se-unen-a-la-provincia-de-europa\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/maristeurope.eu\\\/es\\\/los-padres-maristas-se-unen-a-la-provincia-de-europa\\\/\"},\"author\":{\"name\":\"theo\",\"@id\":\"https:\\\/\\\/maristeurope.eu\\\/es\\\/#\\\/schema\\\/person\\\/f8e95da2dc077ecf7c73937cbebbd209\"},\"headline\":\"Los Padres Maristas se unen a la Provincia de Europa\",\"datePublished\":\"2026-04-22T13:30:00+00:00\",\"dateModified\":\"2026-05-13T13:49:13+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/maristeurope.eu\\\/es\\\/los-padres-maristas-se-unen-a-la-provincia-de-europa\\\/\"},\"wordCount\":537,\"publisher\":{\"@id\":\"https:\\\/\\\/maristeurope.eu\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/maristeurope.eu\\\/es\\\/los-padres-maristas-se-unen-a-la-provincia-de-europa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/maristeurope.eu\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/small-table-lamp-world-map-copy-space-1-scaled.jpg\",\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/maristeurope.eu\\\/es\\\/los-padres-maristas-se-unen-a-la-provincia-de-europa\\\/\",\"url\":\"https:\\\/\\\/maristeurope.eu\\\/es\\\/los-padres-maristas-se-unen-a-la-provincia-de-europa\\\/\",\"name\":\"Los Padres Maristas se unen a la Provincia de Europa - Marist Europe\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/maristeurope.eu\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/maristeurope.eu\\\/es\\\/los-padres-maristas-se-unen-a-la-provincia-de-europa\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/maristeurope.eu\\\/es\\\/los-padres-maristas-se-unen-a-la-provincia-de-europa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/maristeurope.eu\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/small-table-lamp-world-map-copy-space-1-scaled.jpg\",\"datePublished\":\"2026-04-22T13:30:00+00:00\",\"dateModified\":\"2026-05-13T13:49:13+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/maristeurope.eu\\\/es\\\/los-padres-maristas-se-unen-a-la-provincia-de-europa\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/maristeurope.eu\\\/es\\\/los-padres-maristas-se-unen-a-la-provincia-de-europa\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/maristeurope.eu\\\/es\\\/los-padres-maristas-se-unen-a-la-provincia-de-europa\\\/#primaryimage\",\"url\":\"https:\\\/\\\/maristeurope.eu\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/small-table-lamp-world-map-copy-space-1-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/maristeurope.eu\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/small-table-lamp-world-map-copy-space-1-scaled.jpg\",\"width\":2560,\"height\":1707,\"caption\":\"Small table lamp on the world map, copy space, travel concept.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/maristeurope.eu\\\/es\\\/los-padres-maristas-se-unen-a-la-provincia-de-europa\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/maristeurope.eu\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Los Padres Maristas se unen a la Provincia de Europa\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/maristeurope.eu\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/maristeurope.eu\\\/es\\\/\",\"name\":\"Marist Europe\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/maristeurope.eu\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/maristeurope.eu\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/maristeurope.eu\\\/es\\\/#organization\",\"name\":\"Marist Europe\",\"url\":\"https:\\\/\\\/maristeurope.eu\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/maristeurope.eu\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/maristeurope.eu\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/EU-SM-Finalogo-02.png\",\"contentUrl\":\"https:\\\/\\\/maristeurope.eu\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/EU-SM-Finalogo-02.png\",\"width\":150,\"height\":156,\"caption\":\"Marist Europe\"},\"image\":{\"@id\":\"https:\\\/\\\/maristeurope.eu\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/maristeurope.eu\\\/es\\\/#\\\/schema\\\/person\\\/f8e95da2dc077ecf7c73937cbebbd209\",\"name\":\"theo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6709da64a616dd172f3d90d48d6e09e07dca7fed6f6b3fcdd28c01a385bb51f1?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6709da64a616dd172f3d90d48d6e09e07dca7fed6f6b3fcdd28c01a385bb51f1?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6709da64a616dd172f3d90d48d6e09e07dca7fed6f6b3fcdd28c01a385bb51f1?s=96&d=mm&r=g\",\"caption\":\"theo\"},\"url\":\"https:\\\/\\\/maristeurope.eu\\\/es\\\/author\\\/theo\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Los Padres Maristas se unen a la Provincia de Europa - Marist Europe","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/maristeurope.eu\/es\/los-padres-maristas-se-unen-a-la-provincia-de-europa\/","og_locale":"es_ES","og_type":"article","og_title":"Los Padres Maristas se unen a la Provincia de Europa - Marist Europe","og_description":"Nos complace dar la bienvenida a la Provincia de Europa al Padre Christian, que vive con la comunidad de Lyon, y al Padre Clovis, que se une a la comunidad de Londres.","og_url":"https:\/\/maristeurope.eu\/es\/los-padres-maristas-se-unen-a-la-provincia-de-europa\/","og_site_name":"Marist Europe","article_published_time":"2026-04-22T13:30:00+00:00","article_modified_time":"2026-05-13T13:49:13+00:00","og_image":[{"width":2560,"height":1707,"url":"https:\/\/maristeurope.eu\/wp-content\/uploads\/2026\/04\/small-table-lamp-world-map-copy-space-1-scaled.jpg","type":"image\/jpeg"}],"author":"theo","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"theo","Tiempo de lectura":"3 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/maristeurope.eu\/es\/los-padres-maristas-se-unen-a-la-provincia-de-europa\/#article","isPartOf":{"@id":"https:\/\/maristeurope.eu\/es\/los-padres-maristas-se-unen-a-la-provincia-de-europa\/"},"author":{"name":"theo","@id":"https:\/\/maristeurope.eu\/es\/#\/schema\/person\/f8e95da2dc077ecf7c73937cbebbd209"},"headline":"Los Padres Maristas se unen a la Provincia de Europa","datePublished":"2026-04-22T13:30:00+00:00","dateModified":"2026-05-13T13:49:13+00:00","mainEntityOfPage":{"@id":"https:\/\/maristeurope.eu\/es\/los-padres-maristas-se-unen-a-la-provincia-de-europa\/"},"wordCount":537,"publisher":{"@id":"https:\/\/maristeurope.eu\/es\/#organization"},"image":{"@id":"https:\/\/maristeurope.eu\/es\/los-padres-maristas-se-unen-a-la-provincia-de-europa\/#primaryimage"},"thumbnailUrl":"https:\/\/maristeurope.eu\/wp-content\/uploads\/2026\/04\/small-table-lamp-world-map-copy-space-1-scaled.jpg","inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/maristeurope.eu\/es\/los-padres-maristas-se-unen-a-la-provincia-de-europa\/","url":"https:\/\/maristeurope.eu\/es\/los-padres-maristas-se-unen-a-la-provincia-de-europa\/","name":"Los Padres Maristas se unen a la Provincia de Europa - Marist Europe","isPartOf":{"@id":"https:\/\/maristeurope.eu\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/maristeurope.eu\/es\/los-padres-maristas-se-unen-a-la-provincia-de-europa\/#primaryimage"},"image":{"@id":"https:\/\/maristeurope.eu\/es\/los-padres-maristas-se-unen-a-la-provincia-de-europa\/#primaryimage"},"thumbnailUrl":"https:\/\/maristeurope.eu\/wp-content\/uploads\/2026\/04\/small-table-lamp-world-map-copy-space-1-scaled.jpg","datePublished":"2026-04-22T13:30:00+00:00","dateModified":"2026-05-13T13:49:13+00:00","breadcrumb":{"@id":"https:\/\/maristeurope.eu\/es\/los-padres-maristas-se-unen-a-la-provincia-de-europa\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/maristeurope.eu\/es\/los-padres-maristas-se-unen-a-la-provincia-de-europa\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/maristeurope.eu\/es\/los-padres-maristas-se-unen-a-la-provincia-de-europa\/#primaryimage","url":"https:\/\/maristeurope.eu\/wp-content\/uploads\/2026\/04\/small-table-lamp-world-map-copy-space-1-scaled.jpg","contentUrl":"https:\/\/maristeurope.eu\/wp-content\/uploads\/2026\/04\/small-table-lamp-world-map-copy-space-1-scaled.jpg","width":2560,"height":1707,"caption":"Small table lamp on the world map, copy space, travel concept."},{"@type":"BreadcrumbList","@id":"https:\/\/maristeurope.eu\/es\/los-padres-maristas-se-unen-a-la-provincia-de-europa\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/maristeurope.eu\/es\/"},{"@type":"ListItem","position":2,"name":"Los Padres Maristas se unen a la Provincia de Europa"}]},{"@type":"WebSite","@id":"https:\/\/maristeurope.eu\/es\/#website","url":"https:\/\/maristeurope.eu\/es\/","name":"Marist Europe","description":"","publisher":{"@id":"https:\/\/maristeurope.eu\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/maristeurope.eu\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/maristeurope.eu\/es\/#organization","name":"Marist Europe","url":"https:\/\/maristeurope.eu\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/maristeurope.eu\/es\/#\/schema\/logo\/image\/","url":"https:\/\/maristeurope.eu\/wp-content\/uploads\/2024\/10\/EU-SM-Finalogo-02.png","contentUrl":"https:\/\/maristeurope.eu\/wp-content\/uploads\/2024\/10\/EU-SM-Finalogo-02.png","width":150,"height":156,"caption":"Marist Europe"},"image":{"@id":"https:\/\/maristeurope.eu\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/maristeurope.eu\/es\/#\/schema\/person\/f8e95da2dc077ecf7c73937cbebbd209","name":"theo","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/6709da64a616dd172f3d90d48d6e09e07dca7fed6f6b3fcdd28c01a385bb51f1?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/6709da64a616dd172f3d90d48d6e09e07dca7fed6f6b3fcdd28c01a385bb51f1?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6709da64a616dd172f3d90d48d6e09e07dca7fed6f6b3fcdd28c01a385bb51f1?s=96&d=mm&r=g","caption":"theo"},"url":"https:\/\/maristeurope.eu\/es\/author\/theo\/"}]}},"_links":{"self":[{"href":"https:\/\/maristeurope.eu\/es\/wp-json\/wp\/v2\/posts\/10576","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/maristeurope.eu\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/maristeurope.eu\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/maristeurope.eu\/es\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/maristeurope.eu\/es\/wp-json\/wp\/v2\/comments?post=10576"}],"version-history":[{"count":1,"href":"https:\/\/maristeurope.eu\/es\/wp-json\/wp\/v2\/posts\/10576\/revisions"}],"predecessor-version":[{"id":10579,"href":"https:\/\/maristeurope.eu\/es\/wp-json\/wp\/v2\/posts\/10576\/revisions\/10579"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/maristeurope.eu\/es\/wp-json\/wp\/v2\/media\/10555"}],"wp:attachment":[{"href":"https:\/\/maristeurope.eu\/es\/wp-json\/wp\/v2\/media?parent=10576"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/maristeurope.eu\/es\/wp-json\/wp\/v2\/categories?post=10576"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/maristeurope.eu\/es\/wp-json\/wp\/v2\/tags?post=10576"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}