{"id":9966,"date":"2026-03-05T00:44:09","date_gmt":"2026-03-04T23:44:09","guid":{"rendered":"https:\/\/maristeurope.eu\/predigen-fuer-die-missionen\/"},"modified":"2026-03-05T00:45:43","modified_gmt":"2026-03-04T23:45:43","slug":"predigen-fuer-die-missionen","status":"publish","type":"post","link":"https:\/\/maristeurope.eu\/de\/predigen-fuer-die-missionen\/","title":{"rendered":"Predigen f\u00fcr die Missionen"},"content":{"rendered":"\n<p class=\"has-medium-font-size\"><em>Damien Diouf aus der Gemeinde Hull (England) berichtet \u00fcber seinen Dienst<\/em>:  <\/p>\n\n<p class=\"has-medium-font-size\">Seit 2023 predige ich f\u00fcr die Missionen in England. Die Di\u00f6zesen und Dekanate werden j\u00e4hrlich von der Katholischen Missionsvereinigung den Kongregationen zugeteilt, und das erlaubt mir, verschiedene Pfarreien zu besuchen und \u00fcber das Charisma der Maristen und unsere Missionsapostolate zu sprechen. Am Ende der Messe stehe ich mit einem Korb und Umschl\u00e4gen an der T\u00fcr und sammle Geld, das schlie\u00dflich \u00fcber die Generalverwaltung in Rom verteilt wird.  <\/p>\n\n<p class=\"has-medium-font-size\">Mein Hintergrund in Afrika sowie unsere historischen Dokumente wie die herausgegebenen Briefe der Missionare sind eine gro\u00dfe Hilfe. <strong><em>Trotz ihrer geringen Gr\u00f6\u00dfe und ihres fortgeschrittenen Alters zeigen die Pfarrgemeinden ein echtes Interesse an der Mission<\/em><\/strong>Dies bietet die Gelegenheit, sich mit den Pfarrgemeinden und ihren Pfarrern auszutauschen, die oft allein sind, kurz vor der Pensionierung stehen und gesundheitliche Probleme haben.<\/p>\n\n<p class=\"has-medium-font-size\">Im April letzten Jahres bat mich Pater Kevin, unser Provinzial, mich im Bereich der Berufungen in England zu engagieren. Im August nahm ich an einem Jugendfestival in Ampleforth, im Norden Englands, teil und traf den Koordinator des Nationalen Berufungsb\u00fcros der Katholischen Bischofskonferenz in England und Wales. Dies erm\u00f6glichte mir im November 2025 die Teilnahme an einem nationalen Treffen von <strong><em>Berufungspromotoren <\/em><\/strong>teilzunehmen, das er organisierte, mit einem interessanten Vortrag eines spanischen Claretiners. Bei diesem Treffen schloss ich mich dem n\u00f6rdlichen Netzwerk an, das regelm\u00e4\u00dfig \u00fcber die Berufungspastoral von Ordensleuten nachdenkt, die junge Menschen in der Universit\u00e4tsseelsorge begleiten. Sp\u00e4ter schloss ich mich unserem Maristen-Team in London an und wir bereiten ein spannendes Berufungswochenende f\u00fcr junge M\u00e4nner vor, das Anfang September 2026 in Notre Dame de France stattfinden soll.       <\/p>\n\n<p class=\"has-medium-font-size\"><em>Damien Diouf sm<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Damien Diouf berichtet \u00fcber seinen Dienst, indem er Gemeinden besucht und \u00fcber das maristische Charisma und unsere missionarischen Apostolate spricht&#8230;<\/p>\n","protected":false},"author":3,"featured_media":9954,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[51],"tags":[],"class_list":["post-9966","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nicht-kategorisiert"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Predigen f\u00fcr die Missionen - Marist Europe<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/maristeurope.eu\/de\/predigen-fuer-die-missionen\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Predigen f\u00fcr die Missionen - Marist Europe\" \/>\n<meta property=\"og:description\" content=\"Damien Diouf berichtet \u00fcber seinen Dienst, indem er Gemeinden besucht und \u00fcber das maristische Charisma und unsere missionarischen Apostolate spricht...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/maristeurope.eu\/de\/predigen-fuer-die-missionen\/\" \/>\n<meta property=\"og:site_name\" content=\"Marist Europe\" \/>\n<meta property=\"article:published_time\" content=\"2026-03-04T23:44:09+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-04T23:45:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/maristeurope.eu\/wp-content\/uploads\/2026\/03\/IMG-20240426-WA0012.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2048\" \/>\n\t<meta property=\"og:image:height\" content=\"1536\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Anne Marie Salgo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Anne Marie Salgo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/maristeurope.eu\\\/de\\\/predigen-fuer-die-missionen\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/maristeurope.eu\\\/de\\\/predigen-fuer-die-missionen\\\/\"},\"author\":{\"name\":\"Anne Marie Salgo\",\"@id\":\"https:\\\/\\\/maristeurope.eu\\\/de\\\/#\\\/schema\\\/person\\\/52ef67935880edd2768565651118bee9\"},\"headline\":\"Predigen f\u00fcr die Missionen\",\"datePublished\":\"2026-03-04T23:44:09+00:00\",\"dateModified\":\"2026-03-04T23:45:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/maristeurope.eu\\\/de\\\/predigen-fuer-die-missionen\\\/\"},\"wordCount\":285,\"publisher\":{\"@id\":\"https:\\\/\\\/maristeurope.eu\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/maristeurope.eu\\\/de\\\/predigen-fuer-die-missionen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/maristeurope.eu\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/IMG-20240426-WA0012.jpg\",\"articleSection\":[\"Nicht kategorisiert\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/maristeurope.eu\\\/de\\\/predigen-fuer-die-missionen\\\/\",\"url\":\"https:\\\/\\\/maristeurope.eu\\\/de\\\/predigen-fuer-die-missionen\\\/\",\"name\":\"Predigen f\u00fcr die Missionen - Marist Europe\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/maristeurope.eu\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/maristeurope.eu\\\/de\\\/predigen-fuer-die-missionen\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/maristeurope.eu\\\/de\\\/predigen-fuer-die-missionen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/maristeurope.eu\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/IMG-20240426-WA0012.jpg\",\"datePublished\":\"2026-03-04T23:44:09+00:00\",\"dateModified\":\"2026-03-04T23:45:43+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/maristeurope.eu\\\/de\\\/predigen-fuer-die-missionen\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/maristeurope.eu\\\/de\\\/predigen-fuer-die-missionen\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/maristeurope.eu\\\/de\\\/predigen-fuer-die-missionen\\\/#primaryimage\",\"url\":\"https:\\\/\\\/maristeurope.eu\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/IMG-20240426-WA0012.jpg\",\"contentUrl\":\"https:\\\/\\\/maristeurope.eu\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/IMG-20240426-WA0012.jpg\",\"width\":2048,\"height\":1536},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/maristeurope.eu\\\/de\\\/predigen-fuer-die-missionen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/maristeurope.eu\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Predigen f\u00fcr die Missionen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/maristeurope.eu\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/maristeurope.eu\\\/de\\\/\",\"name\":\"Marist Europe\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/maristeurope.eu\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/maristeurope.eu\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/maristeurope.eu\\\/de\\\/#organization\",\"name\":\"Marist Europe\",\"url\":\"https:\\\/\\\/maristeurope.eu\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/maristeurope.eu\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/maristeurope.eu\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/EU-SM-Finalogo-02.png\",\"contentUrl\":\"https:\\\/\\\/maristeurope.eu\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/EU-SM-Finalogo-02.png\",\"width\":150,\"height\":156,\"caption\":\"Marist Europe\"},\"image\":{\"@id\":\"https:\\\/\\\/maristeurope.eu\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/maristeurope.eu\\\/de\\\/#\\\/schema\\\/person\\\/52ef67935880edd2768565651118bee9\",\"name\":\"Anne Marie Salgo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/63bc5f7f74a90bb8d99eaaf8206d8217d780934d9a9659350347a36f2698fe6b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/63bc5f7f74a90bb8d99eaaf8206d8217d780934d9a9659350347a36f2698fe6b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/63bc5f7f74a90bb8d99eaaf8206d8217d780934d9a9659350347a36f2698fe6b?s=96&d=mm&r=g\",\"caption\":\"Anne Marie Salgo\"},\"url\":\"https:\\\/\\\/maristeurope.eu\\\/de\\\/author\\\/anne\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Predigen f\u00fcr die Missionen - Marist Europe","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/maristeurope.eu\/de\/predigen-fuer-die-missionen\/","og_locale":"de_DE","og_type":"article","og_title":"Predigen f\u00fcr die Missionen - Marist Europe","og_description":"Damien Diouf berichtet \u00fcber seinen Dienst, indem er Gemeinden besucht und \u00fcber das maristische Charisma und unsere missionarischen Apostolate spricht...","og_url":"https:\/\/maristeurope.eu\/de\/predigen-fuer-die-missionen\/","og_site_name":"Marist Europe","article_published_time":"2026-03-04T23:44:09+00:00","article_modified_time":"2026-03-04T23:45:43+00:00","og_image":[{"width":2048,"height":1536,"url":"https:\/\/maristeurope.eu\/wp-content\/uploads\/2026\/03\/IMG-20240426-WA0012.jpg","type":"image\/jpeg"}],"author":"Anne Marie Salgo","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Anne Marie Salgo","Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/maristeurope.eu\/de\/predigen-fuer-die-missionen\/#article","isPartOf":{"@id":"https:\/\/maristeurope.eu\/de\/predigen-fuer-die-missionen\/"},"author":{"name":"Anne Marie Salgo","@id":"https:\/\/maristeurope.eu\/de\/#\/schema\/person\/52ef67935880edd2768565651118bee9"},"headline":"Predigen f\u00fcr die Missionen","datePublished":"2026-03-04T23:44:09+00:00","dateModified":"2026-03-04T23:45:43+00:00","mainEntityOfPage":{"@id":"https:\/\/maristeurope.eu\/de\/predigen-fuer-die-missionen\/"},"wordCount":285,"publisher":{"@id":"https:\/\/maristeurope.eu\/de\/#organization"},"image":{"@id":"https:\/\/maristeurope.eu\/de\/predigen-fuer-die-missionen\/#primaryimage"},"thumbnailUrl":"https:\/\/maristeurope.eu\/wp-content\/uploads\/2026\/03\/IMG-20240426-WA0012.jpg","articleSection":["Nicht kategorisiert"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/maristeurope.eu\/de\/predigen-fuer-die-missionen\/","url":"https:\/\/maristeurope.eu\/de\/predigen-fuer-die-missionen\/","name":"Predigen f\u00fcr die Missionen - Marist Europe","isPartOf":{"@id":"https:\/\/maristeurope.eu\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/maristeurope.eu\/de\/predigen-fuer-die-missionen\/#primaryimage"},"image":{"@id":"https:\/\/maristeurope.eu\/de\/predigen-fuer-die-missionen\/#primaryimage"},"thumbnailUrl":"https:\/\/maristeurope.eu\/wp-content\/uploads\/2026\/03\/IMG-20240426-WA0012.jpg","datePublished":"2026-03-04T23:44:09+00:00","dateModified":"2026-03-04T23:45:43+00:00","breadcrumb":{"@id":"https:\/\/maristeurope.eu\/de\/predigen-fuer-die-missionen\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/maristeurope.eu\/de\/predigen-fuer-die-missionen\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/maristeurope.eu\/de\/predigen-fuer-die-missionen\/#primaryimage","url":"https:\/\/maristeurope.eu\/wp-content\/uploads\/2026\/03\/IMG-20240426-WA0012.jpg","contentUrl":"https:\/\/maristeurope.eu\/wp-content\/uploads\/2026\/03\/IMG-20240426-WA0012.jpg","width":2048,"height":1536},{"@type":"BreadcrumbList","@id":"https:\/\/maristeurope.eu\/de\/predigen-fuer-die-missionen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/maristeurope.eu\/de\/"},{"@type":"ListItem","position":2,"name":"Predigen f\u00fcr die Missionen"}]},{"@type":"WebSite","@id":"https:\/\/maristeurope.eu\/de\/#website","url":"https:\/\/maristeurope.eu\/de\/","name":"Marist Europe","description":"","publisher":{"@id":"https:\/\/maristeurope.eu\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/maristeurope.eu\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/maristeurope.eu\/de\/#organization","name":"Marist Europe","url":"https:\/\/maristeurope.eu\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/maristeurope.eu\/de\/#\/schema\/logo\/image\/","url":"https:\/\/maristeurope.eu\/wp-content\/uploads\/2024\/10\/EU-SM-Finalogo-02.png","contentUrl":"https:\/\/maristeurope.eu\/wp-content\/uploads\/2024\/10\/EU-SM-Finalogo-02.png","width":150,"height":156,"caption":"Marist Europe"},"image":{"@id":"https:\/\/maristeurope.eu\/de\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/maristeurope.eu\/de\/#\/schema\/person\/52ef67935880edd2768565651118bee9","name":"Anne Marie Salgo","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/63bc5f7f74a90bb8d99eaaf8206d8217d780934d9a9659350347a36f2698fe6b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/63bc5f7f74a90bb8d99eaaf8206d8217d780934d9a9659350347a36f2698fe6b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/63bc5f7f74a90bb8d99eaaf8206d8217d780934d9a9659350347a36f2698fe6b?s=96&d=mm&r=g","caption":"Anne Marie Salgo"},"url":"https:\/\/maristeurope.eu\/de\/author\/anne\/"}]}},"_links":{"self":[{"href":"https:\/\/maristeurope.eu\/de\/wp-json\/wp\/v2\/posts\/9966","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/maristeurope.eu\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/maristeurope.eu\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/maristeurope.eu\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/maristeurope.eu\/de\/wp-json\/wp\/v2\/comments?post=9966"}],"version-history":[{"count":1,"href":"https:\/\/maristeurope.eu\/de\/wp-json\/wp\/v2\/posts\/9966\/revisions"}],"predecessor-version":[{"id":9968,"href":"https:\/\/maristeurope.eu\/de\/wp-json\/wp\/v2\/posts\/9966\/revisions\/9968"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/maristeurope.eu\/de\/wp-json\/wp\/v2\/media\/9954"}],"wp:attachment":[{"href":"https:\/\/maristeurope.eu\/de\/wp-json\/wp\/v2\/media?parent=9966"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/maristeurope.eu\/de\/wp-json\/wp\/v2\/categories?post=9966"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/maristeurope.eu\/de\/wp-json\/wp\/v2\/tags?post=9966"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}